{"id":3380,"date":"2021-08-11T09:36:11","date_gmt":"2021-08-11T09:36:11","guid":{"rendered":"https:\/\/orange-infrared.com\/cookie-richtlinie\/"},"modified":"2021-08-22T12:33:51","modified_gmt":"2021-08-22T12:33:51","slug":"cookie-richtlinie","status":"publish","type":"page","link":"https:\/\/orange-infrared.com\/de\/cookie-richtlinie\/","title":{"rendered":"Cookie-Richtlinie"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3380\" class=\"elementor elementor-3380 elementor-3006\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17e71e3b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17e71e3b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-43d4a3c5\" data-id=\"43d4a3c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f2e2517 elementor-widget elementor-widget-text-editor\" data-id=\"6f2e2517\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>\u00dcber diese Cookie-Richtlinie<\/strong><\/h3>\n<p>Diese Cookie-Richtlinie erkl\u00e4rt, was Cookies sind und wie wir sie verwenden, welche Arten von Cookies wir verwenden, dh die Informationen, die wir mithilfe von Cookies sammeln und wie diese Informationen verwendet werden, und wie Sie Cookie-Einstellungen verwalten k\u00f6nnen. Weitere Informationen dar\u00fcber, wie wir Ihre personenbezogenen Daten verwenden, speichern und sch\u00fctzen, finden Sie in unserer Datenschutzerkl\u00e4rung.<\/p>\n<p>Sie k\u00f6nnen Ihre Zustimmung zur Cookie-Erkl\u00e4rung auf unserer Website jederzeit \u00e4ndern oder widerrufen<br \/>Lesen Sie in unserer Datenschutzerkl\u00e4rung mehr dar\u00fcber, wer wir sind, wie Sie uns kontaktieren und wie wir personenbezogene Daten verarbeiten.<br \/>Ihre Einwilligung gilt f\u00fcr folgende Domains: orange-infrared.com<br \/><div class=\"cli_user_consent_state\">Dein aktueller Status: Keine Einwilligung erteilt. <a class=\"cli_manage_current_consent\" style=\"cursor:pointer;text-decoration:underline;\">Verwalte deine Einwilligung<\/a> <\/div><\/p>\n<p><strong>Was sind Kekse?<\/strong><br \/>Cookies sind kleine Textdateien, in denen kleine Informationen gespeichert werden. Sie werden beim Laden der Website in Ihrem Browser auf Ihrem Endger\u00e4t gespeichert. Diese Cookies helfen uns, die Website richtig zu funktionieren, sie sicherer zu machen, eine bessere Benutzererfahrung zu bieten und die Leistung der Website zu verstehen und zu analysieren, was funktioniert und wo Verbesserungen erforderlich sind.<br \/>Wie verwenden wir Cookies?<\/p>\n<p>Wie die meisten Online-Dienste verwendet unsere Website f\u00fcr verschiedene Zwecke Erstanbieter- und Drittanbieter-Cookies. Cookies von Erstanbietern sind in der Regel f\u00fcr das ordnungsgem\u00e4\u00dfe Funktionieren der Website erforderlich und sammeln keine Ihrer personenbezogenen Daten.<\/p>\n<p>Die auf unserer Website verwendeten Cookies von Drittanbietern sollen uns in erster Linie helfen zu verstehen, wie die Website funktioniert, wie Sie mit unserer Website interagieren, unsere Dienste sicher zu halten, f\u00fcr Sie relevante Anzeigen zu schalten und Ihnen insgesamt einen \u00dcberblick zu geben bessere Erfahrung und verbesserte Benutzererfahrung und helfen, Ihre zuk\u00fcnftigen Interaktionen mit unserer Website zu beschleunigen.<\/p>\n<p><strong>Welche Arten von Cookies verwenden wir?<\/strong><\/p>\n<p>Wesentlich: Einige Cookies sind unerl\u00e4sslich, um die volle Funktionalit\u00e4t unserer Website zu nutzen. Sie erm\u00f6glichen es uns, Benutzersitzungen aufrechtzuerhalten und Sicherheitsrisiken zu vermeiden. Sie sammeln oder speichern keine personenbezogenen Daten. Mit diesen Cookies k\u00f6nnen Sie sich beispielsweise in Ihr Konto einloggen, Produkte in Ihren Warenkorb legen und sicher bezahlen.<\/p>\n<p>Statistik: Diese Cookies speichern Informationen wie die Anzahl der Besucher der Website, die Anzahl der einzelnen Besucher, welche Seiten der Website besucht wurden, die Quelle des Besuchs usw. Diese Daten helfen uns zu verstehen und zu analysieren, wie gut die Website funktioniert und wo Verbesserungsbedarf besteht.<\/p>\n<p>Marketing: Unsere Website zeigt Werbung. Diese Cookies werden verwendet, um die Werbung, die wir Ihnen zeigen, zu personalisieren, damit sie f\u00fcr Sie von Bedeutung ist. Diese Cookies helfen uns auch, die Effizienz dieser Werbekampagnen zu verfolgen.<br \/>Die in diesen Cookies gespeicherten Informationen k\u00f6nnen auch von den Werbe-Drittanbietern verwendet werden, um Ihnen auch auf anderen Websites im Browser Werbung anzuzeigen.<\/p>\n<p>Funktional: Dies sind die Cookies, die bestimmte nicht wesentliche Funktionen auf unserer Website unterst\u00fctzen. Zu diesen Funktionalit\u00e4ten geh\u00f6ren das Einbetten von Inhalten wie Videos oder das Teilen von Inhalten der Website auf Social-Media-Plattformen.<\/p>\n<p>Pr\u00e4ferenzen: Diese Cookies helfen uns, Ihre Einstellungen und Browser-Pr\u00e4ferenzen, wie Sprachpr\u00e4ferenzen, zu speichern, damit Sie bei zuk\u00fcnftigen Besuchen der Website ein besseres und effizienteres Erlebnis haben.<br \/><\/p>\n<p>Wie kann ich Cookie-Einstellungen verwalten?<\/p>\n<p>Wenn Sie sich sp\u00e4ter entscheiden, Ihre Einstellungen w\u00e4hrend Ihrer Browsersitzung zu \u00e4ndern, k\u00f6nnen Sie auf Ihrem Bildschirm auf die Registerkarte &#8220;Datenschutz- und Cookie-Richtlinie&#8221; klicken. Dadurch wird die Einwilligungserkl\u00e4rung erneut angezeigt, sodass Sie Ihre Einstellungen \u00e4ndern oder Ihre Einwilligung vollst\u00e4ndig widerrufen k\u00f6nnen.<\/p>\n<p>Dar\u00fcber hinaus bieten verschiedene Browser unterschiedliche Methoden zum Blockieren und L\u00f6schen von Cookies, die von Websites verwendet werden. Sie k\u00f6nnen Ihre Browsereinstellungen \u00e4ndern, um Cookies zu blockieren\/zu l\u00f6schen. Weitere Informationen zum Verwalten und L\u00f6schen von Cookies finden Sie unter wikipedia.org, www.allaboutcookies.org.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00dcber diese Cookie-Richtlinie Diese Cookie-Richtlinie erkl\u00e4rt, was Cookies sind und wie wir sie verwenden, welche Arten von Cookies wir verwenden, dh die Informationen, die wir mithilfe von Cookies sammeln und wie diese Informationen verwendet werden, und wie Sie Cookie-Einstellungen verwalten k\u00f6nnen. Weitere Informationen dar\u00fcber, wie wir Ihre personenbezogenen Daten verwenden, speichern und sch\u00fctzen, finden Sie &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/orange-infrared.com\/de\/cookie-richtlinie\/\"> <span class=\"screen-reader-text\">Cookie-Richtlinie<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"class_list":["post-3380","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cookie-Richtlinie - Orange Infrared - Heating Solutions<\/title>\n<meta name=\"description\" content=\"\u00dcber diese Cookie-Richtlinie Diese Cookie-Richtlinie erkl\u00e4rt, was Cookies sind und wie wir sie verwenden, welche Arten von Cookies wir verwenden, dh die\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cookie-Richtlinie\" \/>\n<meta property=\"og:description\" content=\"\u00dcber diese Cookie-Richtlinie Diese Cookie-Richtlinie erkl\u00e4rt, was Cookies sind und wie wir sie verwenden, welche Arten von Cookies wir verwenden, dh die\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orange-infrared.com\/de\/cookie-richtlinie\/\" \/>\n<meta property=\"og:site_name\" content=\"Orange Infrared - Heating Solutions\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-22T12:33:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/cookie-richtlinie\\\/\",\"url\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/cookie-richtlinie\\\/\",\"name\":\"Cookie-Richtlinie - Orange Infrared - Heating Solutions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/#website\"},\"datePublished\":\"2021-08-11T09:36:11+00:00\",\"dateModified\":\"2021-08-22T12:33:51+00:00\",\"description\":\"\u00dcber diese Cookie-Richtlinie Diese Cookie-Richtlinie erkl\u00e4rt, was Cookies sind und wie wir sie verwenden, welche Arten von Cookies wir verwenden, dh die\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/cookie-richtlinie\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orange-infrared.com\\\/de\\\/cookie-richtlinie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/cookie-richtlinie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cookie-Richtlinie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/\",\"name\":\"Orange Infrared - Heating Solutions\",\"description\":\"verwamingsproducten met ge\u00efntegreerde verlichting\",\"publisher\":{\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/#organization\",\"name\":\"Orange Infrared Heating Solutions\",\"url\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orange-infrared.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/cropped-flavico-1.png\",\"contentUrl\":\"https:\\\/\\\/orange-infrared.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/cropped-flavico-1.png\",\"width\":512,\"height\":512,\"caption\":\"Orange Infrared Heating Solutions\"},\"image\":{\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCaSa-j8Uaxa9Mg-5MY1LM1A\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cookie-Richtlinie - Orange Infrared - Heating Solutions","description":"\u00dcber diese Cookie-Richtlinie Diese Cookie-Richtlinie erkl\u00e4rt, was Cookies sind und wie wir sie verwenden, welche Arten von Cookies wir verwenden, dh die","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"de_DE","og_type":"article","og_title":"Cookie-Richtlinie","og_description":"\u00dcber diese Cookie-Richtlinie Diese Cookie-Richtlinie erkl\u00e4rt, was Cookies sind und wie wir sie verwenden, welche Arten von Cookies wir verwenden, dh die","og_url":"https:\/\/orange-infrared.com\/de\/cookie-richtlinie\/","og_site_name":"Orange Infrared - Heating Solutions","article_modified_time":"2021-08-22T12:33:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/orange-infrared.com\/de\/cookie-richtlinie\/","url":"https:\/\/orange-infrared.com\/de\/cookie-richtlinie\/","name":"Cookie-Richtlinie - Orange Infrared - Heating Solutions","isPartOf":{"@id":"https:\/\/orange-infrared.com\/de\/#website"},"datePublished":"2021-08-11T09:36:11+00:00","dateModified":"2021-08-22T12:33:51+00:00","description":"\u00dcber diese Cookie-Richtlinie Diese Cookie-Richtlinie erkl\u00e4rt, was Cookies sind und wie wir sie verwenden, welche Arten von Cookies wir verwenden, dh die","breadcrumb":{"@id":"https:\/\/orange-infrared.com\/de\/cookie-richtlinie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orange-infrared.com\/de\/cookie-richtlinie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/orange-infrared.com\/de\/cookie-richtlinie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orange-infrared.com\/de\/"},{"@type":"ListItem","position":2,"name":"Cookie-Richtlinie"}]},{"@type":"WebSite","@id":"https:\/\/orange-infrared.com\/de\/#website","url":"https:\/\/orange-infrared.com\/de\/","name":"Orange Infrared - Heating Solutions","description":"verwamingsproducten met ge\u00efntegreerde verlichting","publisher":{"@id":"https:\/\/orange-infrared.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orange-infrared.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/orange-infrared.com\/de\/#organization","name":"Orange Infrared Heating Solutions","url":"https:\/\/orange-infrared.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/orange-infrared.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/orange-infrared.com\/wp-content\/uploads\/2021\/06\/cropped-flavico-1.png","contentUrl":"https:\/\/orange-infrared.com\/wp-content\/uploads\/2021\/06\/cropped-flavico-1.png","width":512,"height":512,"caption":"Orange Infrared Heating Solutions"},"image":{"@id":"https:\/\/orange-infrared.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCaSa-j8Uaxa9Mg-5MY1LM1A"]}]}},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/orange-infrared.com\/de\/wp-json\/wp\/v2\/pages\/3380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orange-infrared.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/orange-infrared.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/orange-infrared.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/orange-infrared.com\/de\/wp-json\/wp\/v2\/comments?post=3380"}],"version-history":[{"count":2,"href":"https:\/\/orange-infrared.com\/de\/wp-json\/wp\/v2\/pages\/3380\/revisions"}],"predecessor-version":[{"id":3382,"href":"https:\/\/orange-infrared.com\/de\/wp-json\/wp\/v2\/pages\/3380\/revisions\/3382"}],"wp:attachment":[{"href":"https:\/\/orange-infrared.com\/de\/wp-json\/wp\/v2\/media?parent=3380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}