{"id":3503,"date":"2021-07-28T12:22:13","date_gmt":"2021-08-11T21:48:50","guid":{"rendered":"https:\/\/orange-infrared.com\/winkel\/galaxy-heat-light-w2di310iws\/"},"modified":"2022-06-06T15:23:16","modified_gmt":"2022-06-06T15:23:16","slug":"galaxy-heat-light-w2di310iws-2","status":"publish","type":"product","link":"https:\/\/orange-infrared.com\/de\/shop\/galaxy-heat-light-w2di310iws-2\/","title":{"rendered":"Galaxy Heat &amp; Light-W2di310iWS"},"content":{"rendered":"<p><span style=\"color: #333333;\"><strong>Infrarotstrahlung Panel Gr\u00f6\u00dfe ca. 120(l)x50(b) x 4,5(h)cm<\/strong><\/span><br \/>\n\u2022 das Galaxy Panel hat eine Heizleistung von ca. 500 Watt und eignet sich zur Hauptheizung von R\u00e4umen bis 10m2 Grundfl\u00e4che (B\u00e4der 5-7 m2)<br \/>\n\u2022 Oberfl\u00e4chenstruktur: glatt<br \/>\n\u2022 Farbe: Standardwei\u00df<br \/>\n\u2022 Qualit\u00e4t: Klasse 1 (h\u00f6chste Umwandlung in Infrarotstrahlung) durch Carbon\/Graphen (Nano) Infrarotstrahlungselement (Infrarotpanel)<br \/>\n\u2022 besonders geeignet zur Zusatz- oder Hauptheizung des Badezimmers oder anderer R\u00e4ume<br \/>\n\u2022 attraktives Design, rahmenlose und schr\u00e4ge R\u00fcckseiten f\u00fcr einen schlanken \u201eFloating-Effekt\u201c<br \/>\n\u2022 sehr leicht, nur 6 kg und daher an fast allen Decken montierbar<br \/>\n\u2022 die Au\u00dfenseite des Paneels inklusive Heizelement ist aus Kunststoff und somit korrosionsfrei, IP-Klasse 44, durch diese Kunststoffkonstruktion ist keine Erdung erforderlich<br \/>\n\u2022 das Element ist eine 100% wartungsfreie Heizung (au\u00dfer bei Batteriewechsel)<br \/>\n\u2022 Anschluss an vorhandene Lichtpunktverkabelung: 2-adrig: Neutralleiter (blau) und Schaltdraht (schwarz) f\u00fcr die Installation, Heizung und Beleuchtung werden getrennt geschaltet, heizen drahtlos, die Beleuchtung mit vorhandener Verkabelung<br \/>\n\u2022 die Heizung schaltet sich mit dem kabellosen programmierbaren Thermostat ein, der \u00fcber eine App gesteuert werden kann, Basis-LCD-Displaytyp: 310iRF, kann auch manuell bedient werden (Batterien 2x AA enthalten), Ein\/Aus ist auf dem Display und \u00fcber das Signal sichtbar LED an der Seite des Panels (einmal an der Vorderseite)<br \/>\n\u2022 Die integrierte Beleuchtung besteht aus zwei sparsamen (A+) LED-Lampen, Verbrauch ca. 14 Watt gesamt (920 Lm gesamt, vergleichbar mit 80 Watt traditionell), Lichtfarbe: warmwei\u00df 2.700K, Beleuchtungswinkel: 110 Grad System: linear dimmbare LED<br \/>\n\u2022 du schaltest die Beleuchtung \u00fcber den vorhandenen Wandschalter, somit entf\u00e4llt der Batteriewechsel und du beh\u00e4ltst dein eigenes Schaltmaterial, die Timerfunktion entf\u00e4llt<br \/>\n\u2022 Die Montage\/Installation besteht im Allgemeinen aus dem Anbringen der Bohrschablone, dem Bohren von 4 L\u00f6chern, dem Anbringen von D\u00fcbeln und Befestigungsschrauben, dem Anschlie\u00dfen der Deckenverkabelung an das Panel und dem Anbringen von Wandschalter und Thermostat. Dies kann in der Regel innerhalb von 2 Stunden erreicht werden<br \/>\n\u2022 Lieferung komplett mit Anleitung, Bohr-\/Montageschablone und Befestigungselementen<br \/>\n\u2022 Sie erhalten 12 Jahre Produktgarantie auf das Galaxy-Heizelement, 5 Jahre auf die anderen Elemente im Paket<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"color: #333333;\"><strong>Infrarot-Heizpaneel mit integrierter Beleuchtung:<\/strong><\/span><br \/>\n\u2022 Abmessungen: 50 (B) x 120 (L) x 4,5 (H) cm<br \/>\n\u2022 Heizleistung : 500 Watt mittels Carbon-Grafen (Heizelement), zu beheizende Fl\u00e4che bis 10m2<br \/>\n\u2022 Oberfl\u00e4che: glatt<br \/>\n\u2022 Farbe: Standardwei\u00df<br \/>\n\u2022 Zweileiter-Stromversorgung (Neutralleiter, Phasenleiter)<br \/>\n\u2022 Beleuchtungsart: direkter 2x LED-Spot, linear dimmbare LED<br \/>\n\u2022 Beleuchtung ein\/aus: Beleuchtung ein\/aus: Sie schalten die Beleuchtung \u00fcber den mitgelieferten Funk-Dimmer (Ein-Knopf-Batterie inklusive) Wandschalter 80x80x15mm Aufputz, zur Montage auf eine vorhandene Wandsteckdose oder an anderer Stelle<br \/>\n\u2022 Heizung ein\/aus: voll programmierbarer drahtloser WiFi-Thermostat-Basis-LCD-Bildschirm<br \/>\n\u2022 komplett mit: Befestigungsmaterial, Bohrschablone, Handbuch, Verpackung-Versandkosten<\/p>\n","protected":false},"featured_media":2804,"template":"","meta":{"_monsterinsights_skip_tracking":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"product_brand":[],"product_cat":[71],"product_tag":[79],"class_list":["post-3503","product","type-product","status-publish","has-post-thumbnail","product_cat-galaxy-heat-light-de","product_tag-2-kabel","pa_kleur-paneel-standardfarbe-weis-de","pa_type-aansluiting-2-leiter-standard","pa_type-schakelaar-verlichting-funk-wandschalter","pa_type-thermostaat-wifi-thermostat-programmierbar-310irf","pa_type-verlichting-direkte-beleuchtung-durch-led-strahler","desktop-align-left","tablet-align-left","mobile-align-left","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Galaxy Heat &amp; Light-W2di310iWS - Orange Infrared - Heating Solutions<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orange-infrared.com\/de\/shop\/galaxy-heat-light-w2di310iws-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Galaxy Heat &amp; Light-W2di310iWS\" \/>\n<meta property=\"og:description\" content=\"Infrarot-Heizpaneel mit integrierter Beleuchtung: \u2022 Abmessungen: 50 (B) x 120 (L) x 4,5 (H) cm \u2022 Heizleistung : 500 Watt mittels Carbon-Grafen (Heizelement), zu beheizende Fl\u00e4che bis 10m2 \u2022 Oberfl\u00e4che: glatt \u2022 Farbe: Standardwei\u00df \u2022 Zweileiter-Stromversorgung (Neutralleiter, Phasenleiter) \u2022 Beleuchtungsart: direkter 2x LED-Spot, linear dimmbare LED \u2022 Beleuchtung ein\/aus: Beleuchtung ein\/aus: Sie schalten die Beleuchtung \u00fcber den mitgelieferten Funk-Dimmer (Ein-Knopf-Batterie inklusive) Wandschalter 80x80x15mm Aufputz, zur Montage auf eine vorhandene Wandsteckdose oder an anderer Stelle \u2022 Heizung ein\/aus: voll programmierbarer drahtloser WiFi-Thermostat-Basis-LCD-Bildschirm \u2022 komplett mit: Befestigungsmaterial, Bohrschablone, Handbuch, Verpackung-Versandkosten\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orange-infrared.com\/de\/shop\/galaxy-heat-light-w2di310iws-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Orange Infrared - Heating Solutions\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-06T15:23:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/orange-infrared.com\/wp-content\/uploads\/2021\/06\/galaxy-HL.jpg?fit=921%2C612&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"921\" \/>\n\t<meta property=\"og:image:height\" content=\"612\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/shop\\\/galaxy-heat-light-w2di310iws-2\\\/\",\"url\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/shop\\\/galaxy-heat-light-w2di310iws-2\\\/\",\"name\":\"Galaxy Heat &amp; Light-W2di310iWS - Orange Infrared - Heating Solutions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/shop\\\/galaxy-heat-light-w2di310iws-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/shop\\\/galaxy-heat-light-w2di310iws-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/orange-infrared.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/galaxy-HL.jpg?fit=921%2C612&ssl=1\",\"datePublished\":\"2021-08-11T21:48:50+00:00\",\"dateModified\":\"2022-06-06T15:23:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/shop\\\/galaxy-heat-light-w2di310iws-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orange-infrared.com\\\/de\\\/shop\\\/galaxy-heat-light-w2di310iws-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/shop\\\/galaxy-heat-light-w2di310iws-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/orange-infrared.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/galaxy-HL.jpg?fit=921%2C612&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/orange-infrared.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/galaxy-HL.jpg?fit=921%2C612&ssl=1\",\"width\":921,\"height\":612,\"caption\":\"Infrarot-Panel Galaxie W\u00e4rme &amp; Licht 500Watt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/shop\\\/galaxy-heat-light-w2di310iws-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Winkel\",\"item\":\"https:\\\/\\\/orange-infrared.com\\\/winkel\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Galaxy Heat &amp; Light-W2di310iWS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/\",\"name\":\"Orange Infrared - Heating Solutions\",\"description\":\"verwamingsproducten met ge\u00efntegreerde verlichting\",\"publisher\":{\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/#organization\",\"name\":\"Orange Infrared Heating Solutions\",\"url\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orange-infrared.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/cropped-flavico-1.png\",\"contentUrl\":\"https:\\\/\\\/orange-infrared.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/cropped-flavico-1.png\",\"width\":512,\"height\":512,\"caption\":\"Orange Infrared Heating Solutions\"},\"image\":{\"@id\":\"https:\\\/\\\/orange-infrared.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCaSa-j8Uaxa9Mg-5MY1LM1A\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Galaxy Heat &amp; Light-W2di310iWS - Orange Infrared - Heating Solutions","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orange-infrared.com\/de\/shop\/galaxy-heat-light-w2di310iws-2\/","og_locale":"de_DE","og_type":"article","og_title":"Galaxy Heat &amp; Light-W2di310iWS","og_description":"Infrarot-Heizpaneel mit integrierter Beleuchtung: \u2022 Abmessungen: 50 (B) x 120 (L) x 4,5 (H) cm \u2022 Heizleistung : 500 Watt mittels Carbon-Grafen (Heizelement), zu beheizende Fl\u00e4che bis 10m2 \u2022 Oberfl\u00e4che: glatt \u2022 Farbe: Standardwei\u00df \u2022 Zweileiter-Stromversorgung (Neutralleiter, Phasenleiter) \u2022 Beleuchtungsart: direkter 2x LED-Spot, linear dimmbare LED \u2022 Beleuchtung ein\/aus: Beleuchtung ein\/aus: Sie schalten die Beleuchtung \u00fcber den mitgelieferten Funk-Dimmer (Ein-Knopf-Batterie inklusive) Wandschalter 80x80x15mm Aufputz, zur Montage auf eine vorhandene Wandsteckdose oder an anderer Stelle \u2022 Heizung ein\/aus: voll programmierbarer drahtloser WiFi-Thermostat-Basis-LCD-Bildschirm \u2022 komplett mit: Befestigungsmaterial, Bohrschablone, Handbuch, Verpackung-Versandkosten","og_url":"https:\/\/orange-infrared.com\/de\/shop\/galaxy-heat-light-w2di310iws-2\/","og_site_name":"Orange Infrared - Heating Solutions","article_modified_time":"2022-06-06T15:23:16+00:00","og_image":[{"width":921,"height":612,"url":"https:\/\/i0.wp.com\/orange-infrared.com\/wp-content\/uploads\/2021\/06\/galaxy-HL.jpg?fit=921%2C612&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/orange-infrared.com\/de\/shop\/galaxy-heat-light-w2di310iws-2\/","url":"https:\/\/orange-infrared.com\/de\/shop\/galaxy-heat-light-w2di310iws-2\/","name":"Galaxy Heat &amp; Light-W2di310iWS - Orange Infrared - Heating Solutions","isPartOf":{"@id":"https:\/\/orange-infrared.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orange-infrared.com\/de\/shop\/galaxy-heat-light-w2di310iws-2\/#primaryimage"},"image":{"@id":"https:\/\/orange-infrared.com\/de\/shop\/galaxy-heat-light-w2di310iws-2\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/orange-infrared.com\/wp-content\/uploads\/2021\/06\/galaxy-HL.jpg?fit=921%2C612&ssl=1","datePublished":"2021-08-11T21:48:50+00:00","dateModified":"2022-06-06T15:23:16+00:00","breadcrumb":{"@id":"https:\/\/orange-infrared.com\/de\/shop\/galaxy-heat-light-w2di310iws-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orange-infrared.com\/de\/shop\/galaxy-heat-light-w2di310iws-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/orange-infrared.com\/de\/shop\/galaxy-heat-light-w2di310iws-2\/#primaryimage","url":"https:\/\/i0.wp.com\/orange-infrared.com\/wp-content\/uploads\/2021\/06\/galaxy-HL.jpg?fit=921%2C612&ssl=1","contentUrl":"https:\/\/i0.wp.com\/orange-infrared.com\/wp-content\/uploads\/2021\/06\/galaxy-HL.jpg?fit=921%2C612&ssl=1","width":921,"height":612,"caption":"Infrarot-Panel Galaxie W\u00e4rme &amp; Licht 500Watt"},{"@type":"BreadcrumbList","@id":"https:\/\/orange-infrared.com\/de\/shop\/galaxy-heat-light-w2di310iws-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orange-infrared.com\/de\/"},{"@type":"ListItem","position":2,"name":"Winkel","item":"https:\/\/orange-infrared.com\/winkel\/"},{"@type":"ListItem","position":3,"name":"Galaxy Heat &amp; Light-W2di310iWS"}]},{"@type":"WebSite","@id":"https:\/\/orange-infrared.com\/de\/#website","url":"https:\/\/orange-infrared.com\/de\/","name":"Orange Infrared - Heating Solutions","description":"verwamingsproducten met ge\u00efntegreerde verlichting","publisher":{"@id":"https:\/\/orange-infrared.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orange-infrared.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/orange-infrared.com\/de\/#organization","name":"Orange Infrared Heating Solutions","url":"https:\/\/orange-infrared.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/orange-infrared.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/orange-infrared.com\/wp-content\/uploads\/2021\/06\/cropped-flavico-1.png","contentUrl":"https:\/\/orange-infrared.com\/wp-content\/uploads\/2021\/06\/cropped-flavico-1.png","width":512,"height":512,"caption":"Orange Infrared Heating Solutions"},"image":{"@id":"https:\/\/orange-infrared.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCaSa-j8Uaxa9Mg-5MY1LM1A"]}]}},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/orange-infrared.com\/de\/wp-json\/wp\/v2\/product\/3503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orange-infrared.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/orange-infrared.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orange-infrared.com\/de\/wp-json\/wp\/v2\/media\/2804"}],"wp:attachment":[{"href":"https:\/\/orange-infrared.com\/de\/wp-json\/wp\/v2\/media?parent=3503"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/orange-infrared.com\/de\/wp-json\/wp\/v2\/product_brand?post=3503"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/orange-infrared.com\/de\/wp-json\/wp\/v2\/product_cat?post=3503"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/orange-infrared.com\/de\/wp-json\/wp\/v2\/product_tag?post=3503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}